{"id":1077,"date":"2025-11-06T18:40:00","date_gmt":"2025-11-06T21:40:00","guid":{"rendered":"https:\/\/diariodaregiao.audiencelabs.com.br\/?p=1077"},"modified":"2025-12-04T10:23:30","modified_gmt":"2025-12-04T13:23:30","slug":"nem-os-biologos-conseguiram-explicar-a-volta-de-ave-extinta-ha-125-anos","status":"publish","type":"post","link":"https:\/\/diariodaregiao.audiencelabs.com.br\/nem-os-biologos-conseguiram-explicar-a-volta-de-ave-extinta-ha-125-anos\/","title":{"rendered":"Nem os bi\u00f3logos conseguiram explicar a volta de ave extinta h\u00e1 125 anos"},"content":{"rendered":"\n<p>O taca\u00e9-do-sul, uma ave nativa da Nova Zel\u00e2ndia, foi redescoberto em 1948 ap\u00f3s ser considerado extinto desde 1898. Esta descoberta ocorreu nas montanhas de Murchison e marcou o in\u00edcio de um esfor\u00e7o intenso para conservar a esp\u00e9cie. <\/p>\n\n\n\n<p>Desde ent\u00e3o, atrav\u00e9s da implementa\u00e7\u00e3o de programas espec\u00edficos, o taca\u00e9-do-sul foi reintroduzido na Ilha Sul, na Nova Zel\u00e2ndia, destacando-se como um s\u00edmbolo de sucesso na preserva\u00e7\u00e3o de esp\u00e9cies.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A Redescoberta e os Esfor\u00e7os de Conserva\u00e7\u00e3o<\/h2>\n\n\n\n<p>A reintrodu\u00e7\u00e3o do taca\u00e9-do-sul envolveu uma s\u00e9rie de estrat\u00e9gias. Iniciativas como a reprodu\u00e7\u00e3o em cativeiro, cria\u00e7\u00e3o de santu\u00e1rios e controle de predadores invasores foram essenciais. Tais medidas, implementadas por diversas entidades, contribu\u00edram para elevar a popula\u00e7\u00e3o da esp\u00e9cie a cerca de 500 indiv\u00edduos.<\/p>\n\n\n\n<p>Recentemente, 18 aves foram liberadas no Vale de Greenstone, refor\u00e7ando a presen\u00e7a da esp\u00e9cie na natureza e inspirando novas iniciativas de conserva\u00e7\u00e3o. Este n\u00famero representa um avan\u00e7o significativo, demonstrando que planos bem estruturados podem reverter situa\u00e7\u00f5es cr\u00edticas de quase extin\u00e7\u00e3o.<\/p>\n\n\n<style>@media (min-width: 992px) {\n    .recomendadorV2Area1 {\n        width: 280px;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n        width: calc(100% - 280px);\n    }\n}\n\n@media (max-width: 992px) {\n    .recomendadorV2Button {\n        margin: 0 auto;\n    }\n    .recomendadorV2Area {\n        flex-direction: column;\n        text-align: center;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n    }\n}\n\n.recomendadorV2Area {\n    background: #eeeeee3d;\n    border-radius: 10px;\n    padding: 15px;\n    display: flex;\n    margin: 15px auto;\n    border: 1px solid #00000014;\n    max-width: 800px;\n}\n\n.recomendadorV2Area1 img {\n    width: 280px;\n    height: auto;\n    border-radius: 8px;\n}\n\n.linkrecomendadorv2 {\n    text-decoration: none !important;\n}\n\n.recomendadorV2Area2 .recomendadorV2Type {\n    text-transform: uppercase;\n    font-weight: 500;\n    font-size: 11px;\n    letter-spacing: 2px;\n    color: #666;\n    margin: 12px 0;\n    display: block;\n}\n\n.recomendadorV2Title h2 {\n    padding-top: 0px !important;\n    margin: 0px !important;\n    border-left: none !important;\n    padding-left: 0px !important;\n    line-height: 1.3;\n    color: #000 !important;\n    font-size: 24px;\n    margin-bottom: 12px !important;\n}\n\n.recomendadorV2Desc {\n    color: #333;\n    margin: 12px 0px !important;\n    font-size: 15px;\n    line-height: 1.5;\n}\n\n.recomendadorV2Button {\n    width: auto;\n    max-width: 200px;\n    margin: 0;\n    display: inline-flex;\n    align-items: center;\n    background: #1D3557;\n    border-radius: 8px;\n    color: #fff;\n    height: 36px;\n    justify-content: center;\n    text-align: center;\n    font-size: 14px;\n    padding: 0 20px;\n    transition: background-color 0.2s ease;\n}\n\n.recomendadorV2Button:hover {\n    background: #2a4d7a;\n}\n\n.recomendadorV2Button:after {\n    margin-top: -2px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 8px;\n}\n\n.recomendadorV2Alert {\n    text-align: left;\n    font-size: 11px;\n    margin-top: 8px;\n    color: #666;\n}\n\n.recomendadorFixedArea {\n    width: 100%;\n    display: flex;\n    justify-content: center;\n    align-items: center;\n}\n\n@media (min-width: 992px) {\n    #recomendadorFixed {\n        width: 32% !important;\n        left: 5%;\n    }\n    .recomendadorCloseFixed{\n        right: inherit !important;\n        left: 378px !important;\n    }\n}\n\n#recomendadorFixed {\n    width: 90%;\n    box-shadow: 0 10px 20px 0px #00000057;\n    display: none;\n    height: 90px;\n    background: #F6F6F6;\n    position: fixed;\n    flex-direction: row;\n    bottom: 10px;\n    z-index: 9999;\n    border-radius: 16px;\n    padding: 7px 10px;\n}\n\n.recomendadorLeftArea {\n    width: 160px;\n}\n\n.recomendadorRightArea h2 {\n    padding-top: 0px;\n    margin: 2px 0px 4px 0px !important;\n    font-weight: 400;\n    text-align: center;\n    padding-left: 0px !important;\n    color: #000 !important;\n    border-left: none !important;\n    line-height: 20px;\n    font-size: 12px !important;\n}\n\n.recomendadorImgFixed {\n    overflow: hidden;\n    padding: 8px 6px;\n    height: 100%;\n}\n\n.recomendadorImgFixed img {\n    height: 100% !important;\n    border-radius: 16px;\n}\n\n.recomendadorRightArea {\n    padding-top: 6px;\n    display: flex;\n    width: calc(100% - 130px);\n    justify-content: space-between;\n    align-items: center;\n    flex-direction: column;\n}\n\n.recomendadorButtonFixed {\n    margin: 0 auto;\n    background: #1D3557;\n    width: 80%;\n    text-align: center;\n    font-size: 10px;\n    color: #FFF;\n    padding: 2px 10px;\n    border-radius: 3px;\n}\n\n.recomendadorButtonFixed:after {\n    margin-top: -3px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 10px;\n}\n\n.recomendadorAlertFixed {\n    font-weight: 400;\n    text-align: center;\n    color: #484848;\n    font-size: 8px;\n}\n\n.recomendadorCloseFixed {\n    z-index: 99999;\n    display: none;\n    right: 0px;\n    left: inherit;\n    bottom: 99px;\n    position: fixed;\n    justify-content: center;\n    background: #F6F6F6;\n    width: 25px;\n    align-items: center;\n    height: 25px;\n    font-weight: 800;\n    border-radius: 50%;\n    border: 1px solid #EBEBEB;\n}\n\n.recomendadorV2Desc{\n    color: #000000;\n    margin: 20px 0px;\n}\n\n@media (max-width: 576px) {\n    .recomendadorV2Area {\n      padding: 10px;\n      max-width: 100%;\n    }\n  \n    .recomendadorV2Area1 img {\n      width: 100%;\n      border-radius: 6px;\n    }\n  \n    .recomendadorV2Area2 .recomendadorV2Type {\n      font-size: 9px;\n      letter-spacing: 1px;\n      margin: 8px 0;\n    }\n  \n    .recomendadorV2Title h2 {\n      font-size: 18px !important;\n      margin-bottom: 8px !important;\n      line-height: 1.2;\n    }\n  \n    .recomendadorV2Desc {\n      font-size: 14px;\n      margin: 8px 0 !important;\n      line-height: 1.4;\n    }\n  \n    .recomendadorV2Button {\n      font-size: 12px;\n      height: 30px;\n      padding: 0 12px;\n      max-width: 160px;\n    }\n  \n    .recomendadorV2Button:after {\n      padding-left: 6px;\n    }\n  }\n  <\/style>\n        <div class=\"lazyblock-recomendador-v2-2jDGz wp-block-lazyblock-recomendador-v2\">\n        <a class=\"linkrecomendadorv2\" href=\"https:\/\/diariodaregiao.com.br\/variedades\/miligrama-do-liquido-mais-caro-do-mundo-custa-o-mesmo-que-um-carro-zero\/?utm_source=lazy\" target=\"_blank\" rel=\"noopener\">\n            <div class=\"recomendadorV2Area\">\n            <div class=\"recomendadorV2Area1\">\n                <div class=\"recomendadorV2Img\">\n                <img class=\"lazyloaded\" decoding=\"async\" src=\"https:\/\/diariodaregiao.com.br\/_midias\/jpg\/2025\/02\/05\/liquido_mais_caro_do_mundo-123456.jpg\" data-src=\"https:\/\/diariodaregiao.com.br\/_midias\/jpg\/2025\/02\/05\/liquido_mais_caro_do_mundo-123456.jpg\" alt=\"\">\n                <\/div>\n            <\/div>\n            <div class=\"recomendadorV2Area2\">\n                <div class=\"recomendadorV2Type\">\n                    <span>Curiosidade rara<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Title\">\n                <h2><span>L\u00edquido vale um carro \ud83d\ude97<\/span><\/h2>\n                <\/div>\n                <div class=\"recomendadorV2Desc\">\n                <span>Descubra por que esse l\u00edquido custa tanto<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Button\">Veja o pre\u00e7o absurdo<\/div>\n                <div class=\"recomendadorV2Alert\"><\/div>\n            <\/div>\n            <\/div>\n        <\/a>\n        <div>\n            <div style=\"z-index:99999;\" id=\"buttonClose\" onclick=\"closeRecomendadorFixed()\">\n            <div class=\"recomendadorCloseFixed\">X<\/div>\n            <\/div>\n            <a href=\"https:\/\/diariodaregiao.com.br\/variedades\/miligrama-do-liquido-mais-caro-do-mundo-custa-o-mesmo-que-um-carro-zero\/?utm_source=lazy\" target=\"_blank\" rel=\"noopener\">\n            <div class=\"recomendadorFixedArea\">\n                <div id=\"recomendadorFixed\">\n                <div class=\"recomendadorLeftArea\">\n                    <div class=\"recomendadorImgFixed\">\n                    <img class=\"lazyload\" decoding=\"async\" src=\"https:\/\/diariodaregiao.com.br\/_midias\/jpg\/2025\/02\/05\/liquido_mais_caro_do_mundo-123456.jpg\" alt=\"\">\n                    <\/div>\n                <\/div>\n                <div class=\"recomendadorRightArea\">\n                    <div class=\"recomendadorTitleFixed\">\n                    <h2><span>L\u00edquido vale um carro \ud83d\ude97<\/span><\/h2>\n                    <\/div>\n                    <div class=\"recomendadorButtonFixed\">Veja o pre\u00e7o absurdo<\/div>\n                    <div class=\"recomendadorAlertFixed\"><\/div>\n                <\/div>\n                <\/div>\n            <\/div>\n            <\/a>\n        <\/div>\n        <\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-content\/uploads\/2025\/11\/Captura-de-tela-2025-10-15-105252.png\" alt=\"\" class=\"wp-image-1079\"\/><figcaption class=\"wp-element-caption\">Cr\u00e9ditos: Reprodu\u00e7\u00e3o <\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Desafios e Significados Culturais<\/h2>\n\n\n\n<p>Apesar do progresso, o taca\u00e9-do-sul permanece vulner\u00e1vel. Como uma ave incapaz de voar com ninhos ao n\u00edvel do solo, enfrenta riscos de predadores como fur\u00f5es e gatos selvagens. Monitoramento cont\u00ednuo \u00e9 essencial para sua prote\u00e7\u00e3o.<\/p>\n\n\n\n<p>Al\u00e9m da import\u00e2ncia biol\u00f3gica, o taca\u00e9-do-sul tem um significado cultural profundo para os Maori, notadamente a tribo Ng\u0101i Tahu. Suas penas, vistas como tesouros espirituais, s\u00e3o um elo cultural significativo. Portanto, sua preserva\u00e7\u00e3o n\u00e3o \u00e9 apenas uma vit\u00f3ria ecol\u00f3gica, mas tamb\u00e9m uma reconex\u00e3o cultural valiosa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Perspectivas de Futuro<\/h2>\n\n\n\n<p>O compromisso com a conserva\u00e7\u00e3o do taca\u00e9-do-sul permanece forte. Planos futuros incluem a expans\u00e3o de sua distribui\u00e7\u00e3o geogr\u00e1fica e a continuidade de estrat\u00e9gias avan\u00e7adas de manejo. A Nova Zel\u00e2ndia segue determinada a garantir condi\u00e7\u00f5es seguras para uma popula\u00e7\u00e3o autossustent\u00e1vel.<\/p>\n\n\n\n<p>A hist\u00f3ria do taca\u00e9-do-sul na conserva\u00e7\u00e3o da biodiversidade sublinha a import\u00e2ncia da persist\u00eancia humana combinada com t\u00e9cnicas inovadoras e tradicionais para a prote\u00e7\u00e3o de esp\u00e9cies amea\u00e7adas. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>O taca\u00e9-do-sul, uma ave nativa da Nova Zel\u00e2ndia, foi redescoberto em 1948 ap\u00f3s ser considerado extinto desde 1898. Esta descoberta ocorreu nas montanhas de Murchison e marcou o in\u00edcio de um esfor\u00e7o intenso para conservar a esp\u00e9cie. Desde ent\u00e3o, atrav\u00e9s da implementa\u00e7\u00e3o de programas espec\u00edficos, o taca\u00e9-do-sul foi reintroduzido na Ilha Sul, na Nova Zel\u00e2ndia, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":1078,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-variedades"],"_links":{"self":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/1077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=1077"}],"version-history":[{"count":4,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/1077\/revisions"}],"predecessor-version":[{"id":4424,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/1077\/revisions\/4424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/1078"}],"wp:attachment":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=1077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=1077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=1077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}