{"id":25167,"date":"2026-05-13T08:44:00","date_gmt":"2026-05-13T11:44:00","guid":{"rendered":"https:\/\/diariodaregiao.audiencelabs.com.br\/?p=25167"},"modified":"2026-05-13T00:28:27","modified_gmt":"2026-05-13T03:28:27","slug":"real-madrid-prepara-dossie-denunciando-o-barcelona-por-corrupcao","status":"publish","type":"post","link":"https:\/\/diariodaregiao.audiencelabs.com.br\/real-madrid-prepara-dossie-denunciando-o-barcelona-por-corrupcao\/","title":{"rendered":"Real Madrid prepara dossi\u00ea denunciando o Barcelona por corrup\u00e7\u00e3o"},"content":{"rendered":"\n<p>Real Madrid prepara um dossi\u00ea para denunciar o Barcelona por corrup\u00e7\u00e3o \u00e0 Uefa ap\u00f3s novas declara\u00e7\u00f5es envolvendo o chamado Caso Negreira. O assunto voltou ao centro das discuss\u00f5es depois de o clube merengue citar pagamentos ligados \u00e0 arbitragem espanhola, justamente em um per\u00edodo que segue cercado por fortes questionamentos.<\/p>\n\n\n\n<p>A declara\u00e7\u00e3o foi feita por Florentino P\u00e9rez, presidente do Real Madrid, durante uma coletiva de imprensa realizada nesta ter\u00e7a-feira. O dirigente aproveitou o momento ap\u00f3s o vice-campeonato de LaLiga para voltar a falar sobre a situa\u00e7\u00e3o envolvendo o maior rival do futebol espanhol.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Florentino P\u00e9rez cita esc\u00e2ndalo hist\u00f3rico<\/h2>\n\n\n\n<p>Segundo Florentino P\u00e9rez, o Real Madrid descobriu h\u00e1 tr\u00eas anos um caso de corrup\u00e7\u00e3o considerado sem precedentes no futebol mundial. O presidente afirmou ainda que o epis\u00f3dio \u00e9 tratado internamente como o maior esc\u00e2ndalo da hist\u00f3ria do esporte, principalmente pelos desdobramentos ligados \u00e0 arbitragem.<\/p>\n\n\n\n<p>O dirigente tamb\u00e9m demonstrou inc\u00f4modo pelo fato de \u00e1rbitros daquele per\u00edodo seguirem atuando em competi\u00e7\u00f5es organizadas pela La Liga. No entendimento do mandat\u00e1rio merengue, a situa\u00e7\u00e3o ainda provoca d\u00favidas relevantes e, at\u00e9 mesmo por isso, exige uma resposta mais firme das autoridades esportivas.<\/p>\n\n\n\n<p>Durante a coletiva, Florentino P\u00e9rez afirmou que o Real Madrid prepara um documento importante para ser enviado imediatamente \u00e0 Uefa. A inten\u00e7\u00e3o do clube espanhol \u00e9 pedir que a entidade ataque o problema pela raiz e trate o Caso Negreira como uma quest\u00e3o importante para o futebol mundial.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Real Madrid quer levar caso \u00e0 Uefa<\/h2>\n\n\n\n<p>As declara\u00e7\u00f5es do presidente do Real Madrid aumentaram ainda mais a tens\u00e3o envolvendo os dois gigantes espanh\u00f3is. O caso mencionado por Florentino P\u00e9rez envolve pagamentos enviados pelo Barcelona a respons\u00e1veis pela arbitragem espanhola entre os anos de 2011 e 2018.<\/p>\n\n\n\n<p>Mesmo sem detalhar quais medidas espera da Uefa, o mandat\u00e1rio refor\u00e7ou que o objetivo do dossi\u00ea \u00e9 provocar uma an\u00e1lise profunda sobre o tema. No entanto, o discurso tamb\u00e9m acabou provocando forte rea\u00e7\u00e3o nos bastidores do Barcelona logo ap\u00f3s a entrevista.<\/p>\n\n\n\n<p>O clube catal\u00e3o informou oficialmente que seu departamento jur\u00eddico j\u00e1 est\u00e1 analisando cuidadosamente as declara\u00e7\u00f5es feitas pelo presidente do Real Madrid. Al\u00e9m disso, o Barcelona afirmou que tamb\u00e9m avalia quais medidas poder\u00e3o ser adotadas diante das acusa\u00e7\u00f5es citadas durante a coletiva.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"598\" src=\"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/51434_06A1BE25ECC7FC6F-1-1024x598.jpg\" alt=\"\" class=\"wp-image-25168\" srcset=\"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/51434_06A1BE25ECC7FC6F-1-1024x598.jpg 1024w, https:\/\/diariodaregiao.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/51434_06A1BE25ECC7FC6F-1-300x175.jpg 300w, https:\/\/diariodaregiao.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/51434_06A1BE25ECC7FC6F-1-768x449.jpg 768w, https:\/\/diariodaregiao.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/51434_06A1BE25ECC7FC6F-1-750x438.jpg 750w, https:\/\/diariodaregiao.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/51434_06A1BE25ECC7FC6F-1-1140x666.jpg 1140w, https:\/\/diariodaregiao.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/51434_06A1BE25ECC7FC6F-1.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9ditos: Divulga\u00e7\u00e3o\/Barcelona (Joan Laporta)<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Barcelona reage ap\u00f3s acusa\u00e7\u00f5es<\/h2>\n\n\n\n<p>Em comunicado divulgado em seu site, o Barcelona destacou que as falas de Florentino P\u00e9rez seguem sob an\u00e1lise do departamento jur\u00eddico do clube. A equipe espanhola afirmou ainda que as acusa\u00e7\u00f5es mencionadas pelo dirigente est\u00e3o sendo avaliadas internamente neste momento.<\/p>\n\n\n\n<p>O comunicado tamb\u00e9m informou que poss\u00edveis posicionamentos e decis\u00f5es ser\u00e3o divulgados apenas quando o Barcelona considerar oportuno. At\u00e9 l\u00e1, justamente para evitar novos desdobramentos p\u00fablicos, o clube preferiu n\u00e3o antecipar quais medidas pretende tomar nos pr\u00f3ximos dias.<\/p>\n\n\n\n<p>Mesmo com a resposta oficial do Barcelona, Florentino P\u00e9rez manteve o discurso adotado durante a coletiva e refor\u00e7ou a gravidade do caso citado pelo Real Madrid. O dirigente entende que o envio do material \u00e0 Uefa pode ampliar a press\u00e3o sobre os respons\u00e1veis pela investiga\u00e7\u00e3o, al\u00e9m de recolocar o debate sobre arbitragem no centro do futebol espanhol.<\/p>\n\n\n\n<p>Enquanto isso, o Real Madrid mant\u00e9m a inten\u00e7\u00e3o de encaminhar o dossi\u00ea \u00e0 Uefa para pressionar por uma solu\u00e7\u00e3o relacionada ao Caso Negreira. Dessa forma, a troca de acusa\u00e7\u00f5es entre os dois rivais espanh\u00f3is ganhou um novo cap\u00edtulo, ampliando ainda mais a repercuss\u00e3o do epis\u00f3dio no futebol europeu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Real Madrid prepara um dossi\u00ea para denunciar o Barcelona por corrup\u00e7\u00e3o \u00e0 Uefa ap\u00f3s novas declara\u00e7\u00f5es envolvendo o chamado Caso Negreira. O assunto voltou ao centro das discuss\u00f5es depois de o clube merengue citar pagamentos ligados \u00e0 arbitragem espanhola, justamente em um per\u00edodo que segue cercado por fortes questionamentos. A declara\u00e7\u00e3o foi feita por Florentino [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":24899,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-25167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-variedades"],"_links":{"self":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/25167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=25167"}],"version-history":[{"count":1,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/25167\/revisions"}],"predecessor-version":[{"id":25169,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/25167\/revisions\/25169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/24899"}],"wp:attachment":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=25167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=25167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=25167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}