{"id":25213,"date":"2026-05-13T14:35:00","date_gmt":"2026-05-13T17:35:00","guid":{"rendered":"https:\/\/diariodaregiao.audiencelabs.com.br\/?p=25213"},"modified":"2026-05-13T13:26:10","modified_gmt":"2026-05-13T16:26:10","slug":"neymar-ganha-duas-chances-finais-de-convencer-ancelotti-e-ir-para-a-copa-do-mundo","status":"publish","type":"post","link":"https:\/\/diariodaregiao.audiencelabs.com.br\/neymar-ganha-duas-chances-finais-de-convencer-ancelotti-e-ir-para-a-copa-do-mundo\/","title":{"rendered":"Neymar ganha duas chances finais de convencer Ancelotti e ir para a Copa do Mundo"},"content":{"rendered":"\n<p>Presente em mais uma pr\u00e9-lista da Sele\u00e7\u00e3o Brasileira, Neymar corre contra o tempo para convencer o t\u00e9cnico Carlo Ancelotti a coloc\u00e1-lo na convoca\u00e7\u00e3o final da Copa. Para isso, o craque tem mais duas grandes chances de mostrar servi\u00e7o dentro de campo pelo Santos.<\/p>\n\n\n\n<p>A primeira delas \u00e9 justamente nesta quarta-feira (13). \u00c0s 19h30 (de Bras\u00edlia) de hoje, o Peixe encara o Coritiba, no Couto Pereira, pela partida de volta da quinta fase da Copa do Brasil. Confirmado no duelo, o astro \u00e9 a grande esperan\u00e7a de classifica\u00e7\u00e3o do time alvinegro &#8211; o primeiro jogo foi 0 a 0.<\/p>\n\n\n\n<p>Em seguida, as equipes voltar\u00e3o a se enfrentar, desta vez pelo Brasileir\u00e3o. O embate acontecer\u00e1 no domingo (17), \u00e0s 11h, na Vila Belmiro. Caso nada aconte\u00e7a logo mais e nenhum problema f\u00edsico seja detectado nos trabalhos dos pr\u00f3ximos dias, o camisa 10 dever\u00e1 estar em campo novamente.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"828\" src=\"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/55201948613_3c80a0c9d2_k-1-e1778689554383-1024x828.jpg\" alt=\"\" class=\"wp-image-25215\" srcset=\"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/55201948613_3c80a0c9d2_k-1-e1778689554383-1024x828.jpg 1024w, https:\/\/diariodaregiao.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/55201948613_3c80a0c9d2_k-1-e1778689554383-300x242.jpg 300w, https:\/\/diariodaregiao.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/55201948613_3c80a0c9d2_k-1-e1778689554383-768x621.jpg 768w, https:\/\/diariodaregiao.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/55201948613_3c80a0c9d2_k-1-e1778689554383-1536x1242.jpg 1536w, https:\/\/diariodaregiao.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/55201948613_3c80a0c9d2_k-1-e1778689554383-750x606.jpg 750w, https:\/\/diariodaregiao.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/55201948613_3c80a0c9d2_k-1-e1778689554383-1140x921.jpg 1140w, https:\/\/diariodaregiao.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/55201948613_3c80a0c9d2_k-1-e1778689554383.jpg 1638w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9ditos: Raul Baretta\/ Santos FC.<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Ou seja, s\u00e3o duas chances de ouro para o capit\u00e3o santista mostrar para Carletto que est\u00e1 bem fisicamente e merece ir para o Mundial. Aos 34 anos de idade, Neymar caminha para os \u00faltimos momentos de sua carreira e sonha com a possibilidade de vestir a camisa amarelinha pela \u00faltima vez em uma Copa do Mundo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Neymar est\u00e1 na pr\u00e9-lista da Sele\u00e7\u00e3o<\/h2>\n\n\n\n<p>Desde que Ancelotti assumiu o comando do selecionado canarinho, o camisa 10 do Santos esteve nas pr\u00e9-listas sempre que saud\u00e1vel. Agora, o mesmo se aplica. O nome dele \u00e9 um dos 55 que comp\u00f5em a chamada \u201clista larga\u201d enviada \u00e0 Fifa na segunda-feira (11).<\/p>\n\n\n\n<p>\u00c9 dessa rela\u00e7\u00e3o que sair\u00e3o os 26 atletas que v\u00e3o representar o pa\u00eds no Mundial. Com os cortes de Est\u00eav\u00e3o e Rodrygo, ambos por les\u00e3o, as esperan\u00e7as do craque de ser lembrado se renovaram. Vale lembrar que, apesar de constar nas listas preliminares, ele nunca foi chamado por Carletto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presente em mais uma pr\u00e9-lista da Sele\u00e7\u00e3o Brasileira, Neymar corre contra o tempo para convencer o t\u00e9cnico Carlo Ancelotti a coloc\u00e1-lo na convoca\u00e7\u00e3o final da Copa. Para isso, o craque tem mais duas grandes chances de mostrar servi\u00e7o dentro de campo pelo Santos. A primeira delas \u00e9 justamente nesta quarta-feira (13). \u00c0s 19h30 (de Bras\u00edlia) [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":25214,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-25213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-variedades"],"_links":{"self":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/25213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=25213"}],"version-history":[{"count":1,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/25213\/revisions"}],"predecessor-version":[{"id":25216,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/25213\/revisions\/25216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/25214"}],"wp:attachment":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=25213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=25213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=25213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}