{"id":29996,"date":"2026-07-14T18:14:45","date_gmt":"2026-07-14T21:14:45","guid":{"rendered":"https:\/\/diariodaregiao.com.br\/variedades\/?p=29996"},"modified":"2026-07-14T18:15:09","modified_gmt":"2026-07-14T21:15:09","slug":"vilao-da-franca-esta-sendo-vendido-por-r-58-milhoes","status":"publish","type":"post","link":"https:\/\/diariodaregiao.com.br\/variedades\/vilao-da-franca-esta-sendo-vendido-por-r-58-milhoes\/","title":{"rendered":"Vil\u00e3o da Fran\u00e7a est\u00e1 sendo vendido por R$ 58 milh\u00f5es"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Lucas Digne est\u00e1 pr\u00f3ximo de iniciar um novo cap\u00edtulo em sua carreira. O lateral-esquerdo da sele\u00e7\u00e3o francesa e do Aston Villa, da Inglaterra, chegou a um acordo para defender o Paris Saint-Germain ap\u00f3s o encerramento da Copa do Mundo. A informa\u00e7\u00e3o foi divulgada pelos jornais franceses <em>L&#8217;Equipe<\/em> e <em>RMC Sport<\/em>, que apontam um v\u00ednculo v\u00e1lido por tr\u00eas temporadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O experiente defensor, de 32 anos, voltar\u00e1 ao clube parisiense cerca de uma d\u00e9cada depois de sua primeira passagem pela equipe. Embora o acerto entre jogador e PSG j\u00e1 esteja encaminhado, a assinatura oficial do contrato dever\u00e1 acontecer somente ap\u00f3s o fim da participa\u00e7\u00e3o da Fran\u00e7a no Mundial, j\u00e1 que Digne segue concentrado com a sele\u00e7\u00e3o na Am\u00e9rica do Norte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O nome do lateral ganhou destaque durante a competi\u00e7\u00e3o por um motivo negativo. Na semifinal, ele cometeu o p\u00eanalti sobre Lamine Yamal em um lance decisivo, epis\u00f3dio que marcou a elimina\u00e7\u00e3o da Fran\u00e7a e gerou in\u00fameras cr\u00edticas por parte da imprensa e dos torcedores. Desde ent\u00e3o, Digne passou a ser um dos personagens mais comentados da campanha francesa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para concretizar a contrata\u00e7\u00e3o, o Paris Saint-Germain dever\u00e1 desembolsar aproximadamente 10 milh\u00f5es de euros, valor equivalente a cerca de R$ 58 milh\u00f5es, correspondente \u00e0 cl\u00e1usula prevista no contrato do jogador com o Aston Villa. A diretoria parisiense considera a experi\u00eancia e a versatilidade do defensor importantes para refor\u00e7ar o elenco na pr\u00f3xima temporada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caso a transfer\u00eancia seja confirmada, Lucas Digne voltar\u00e1 a vestir a camisa do PSG em busca de uma nova fase na carreira, tentando deixar para tr\u00e1s as lembran\u00e7as da elimina\u00e7\u00e3o francesa no Mundial e recuperar o protagonismo em um dos principais clubes do futebol europeu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lucas Digne est\u00e1 pr\u00f3ximo de iniciar um novo cap\u00edtulo em sua carreira. O lateral-esquerdo da sele\u00e7\u00e3o francesa e do Aston Villa, da Inglaterra, chegou a um acordo para defender o Paris Saint-Germain ap\u00f3s o encerramento da Copa do Mundo. A informa\u00e7\u00e3o foi divulgada pelos jornais franceses L&#8217;Equipe e RMC Sport, que apontam um v\u00ednculo v\u00e1lido [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":28700,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-29996","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-variedades"],"_links":{"self":[{"href":"https:\/\/diariodaregiao.com.br\/variedades\/wp-json\/wp\/v2\/posts\/29996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodaregiao.com.br\/variedades\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodaregiao.com.br\/variedades\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodaregiao.com.br\/variedades\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodaregiao.com.br\/variedades\/wp-json\/wp\/v2\/comments?post=29996"}],"version-history":[{"count":1,"href":"https:\/\/diariodaregiao.com.br\/variedades\/wp-json\/wp\/v2\/posts\/29996\/revisions"}],"predecessor-version":[{"id":29997,"href":"https:\/\/diariodaregiao.com.br\/variedades\/wp-json\/wp\/v2\/posts\/29996\/revisions\/29997"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodaregiao.com.br\/variedades\/wp-json\/wp\/v2\/media\/28700"}],"wp:attachment":[{"href":"https:\/\/diariodaregiao.com.br\/variedades\/wp-json\/wp\/v2\/media?parent=29996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodaregiao.com.br\/variedades\/wp-json\/wp\/v2\/categories?post=29996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodaregiao.com.br\/variedades\/wp-json\/wp\/v2\/tags?post=29996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}