{"id":4688,"date":"2025-12-23T10:00:00","date_gmt":"2025-12-23T13:00:00","guid":{"rendered":"https:\/\/diariodaregiao.audiencelabs.com.br\/?p=4688"},"modified":"2025-12-22T15:14:44","modified_gmt":"2025-12-22T18:14:44","slug":"obra-de-r-24-milhoes-que-vai-cortar-a-cidade-fica-pronta-em-marco-de-2026","status":"publish","type":"post","link":"https:\/\/diariodaregiao.audiencelabs.com.br\/obra-de-r-24-milhoes-que-vai-cortar-a-cidade-fica-pronta-em-marco-de-2026\/","title":{"rendered":"Obra de R$ 24 milh\u00f5es que vai cortar a cidade fica pronta em mar\u00e7o de 2026"},"content":{"rendered":"\n<p>O final de ano est\u00e1 chegando e v\u00e1rias cidades brasileiras j\u00e1 est\u00e3o com projetos em andamento pensando no ano de 2026. Uma das cidades daqui, inclusive, vai simplesmente ser praticamente cortada ao meio com esse novo projeto.<\/p>\n\n\n\n<p>O estado do Acre est\u00e1 passando por um constante processo de evolu\u00e7\u00e3o nos \u00faltimos anos, visando &#8220;tirar o atraso&#8221; em muitos projetos que foram deixados de lado. Essa \u00e9 justamente a ideia que vai surgir com um projeto importante para o estado.<\/p>\n\n\n\n<p>Capital do Estado, Rio Branco se prepara para receber o t\u00e3o aguardado viaduto da Associa\u00e7\u00e3o Atl\u00e9tica Banco do Brasil (AABB), que fica localizado na Avenida Cear\u00e1 com a Estrada Dias Martins. A ideia, prevista inicialmente, era de que o projeto fosse finalizado e entregue at\u00e9 o anivers\u00e1rio de funda\u00e7\u00e3o de 143 anos da capital.<\/p>\n\n\n\n<p>Mesmo tendo a tamanha import\u00e2ncia desse projeto em mente, as obras acabaram atrasando consideravelmente e s\u00f3 deve ser finalizada no primeiro trimestre de 2026. Agora, a previs\u00e3o de entrega \u00e9 para o m\u00eas de mar\u00e7o.<\/p>\n\n\n\n<p>Em nota oficial divulgada pela Prefeitura de Rio Branco, fizeram quest\u00e3o de falar sobre o atraso nas obras. De acordo com eles, esse atraso aconteceu por quest\u00f5es log\u00edsticas, e n\u00e3o por nenhum ato de m\u00e1 f\u00e9.<\/p>\n\n\n\n<p>&#8220;Ressaltamos que n\u00e3o houve m\u00e1-f\u00e9 nem por parte da empresa executora, nem da gest\u00e3o municipal. Trata-se de uma situa\u00e7\u00e3o log\u00edstica, considerando tamb\u00e9m a dist\u00e2ncia geogr\u00e1fica do Acre em rela\u00e7\u00e3o aos centros produtores&#8221;, explicou.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Atraso nas obras est\u00e1 causando s\u00e9ries consequ\u00eancias no tr\u00e2nsito<\/h2>\n\n\n\n<p>Apesar de que a constru\u00e7\u00e3o tenha o intuito de melhorar muito a infraestrutura da capital, a verdade \u00e9 que esse atraso est\u00e1 causando muitos preju\u00edzos, principalmente no tr\u00e2nsito. A rotat\u00f3ria que \u00e9 muito utilizada em frente \u00e0\u00a0Associa\u00e7\u00e3o Atl\u00e9tico do Banco do Brasil (AABB) est\u00e1 bloqueada no momento por conta das obras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O final de ano est\u00e1 chegando e v\u00e1rias cidades brasileiras j\u00e1 est\u00e3o com projetos em andamento pensando no ano de 2026. Uma das cidades daqui, inclusive, vai simplesmente ser praticamente cortada ao meio com esse novo projeto. O estado do Acre est\u00e1 passando por um constante processo de evolu\u00e7\u00e3o nos \u00faltimos anos, visando &#8220;tirar o [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":4689,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-variedades"],"_links":{"self":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/4688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=4688"}],"version-history":[{"count":1,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/4688\/revisions"}],"predecessor-version":[{"id":4690,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/4688\/revisions\/4690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/4689"}],"wp:attachment":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=4688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=4688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=4688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}