{"id":8718,"date":"2026-01-09T14:40:00","date_gmt":"2026-01-09T17:40:00","guid":{"rendered":"https:\/\/diariodaregiao.audiencelabs.com.br\/?p=8718"},"modified":"2026-01-08T23:41:22","modified_gmt":"2026-01-09T02:41:22","slug":"cruzeiro-abre-o-bolso-e-desembolsa-r-1945-milhoes-para-comprar-dois-jogadores","status":"publish","type":"post","link":"https:\/\/diariodaregiao.audiencelabs.com.br\/cruzeiro-abre-o-bolso-e-desembolsa-r-1945-milhoes-para-comprar-dois-jogadores\/","title":{"rendered":"Cruzeiro abre o bolso e desembolsa R$ 194,5 milh\u00f5es para comprar dois jogadores"},"content":{"rendered":"\n<p>O Cruzeiro sob a gest\u00e3o da SAF de Pedrinho BH voltou a ser uma das principais for\u00e7as do futebol brasileiro, muito por conta de seu investimento bastante elevado em contrata\u00e7\u00f5es. Se em 2025 o investimento j\u00e1 havia sido pesado, n\u00e3o vem sendo diferente agora em 2026.<\/p>\n\n\n\n<p>Apesar de ainda n\u00e3o ter anunciado nenhum novo refor\u00e7o que tenha sido contratado nessa janela de janeiro, o clube est\u00e1 muito perto de fechar com dois refor\u00e7os, incluindo um de grande impacto. Ao todo, a Raposa deve desembolsar cerca de R$ 194,5 milh\u00f5es.<\/p>\n\n\n\n<p>O primeiro \u00e9 Chico Da Costa, centroavante de 30 anos de idade que pertence ao Cerro Porte\u00f1o, do Paraguai, mas que esteve emprestado ao Mirassol na \u00faltima temporada, agora sendo adquirido pelo Cabuloso por 1 milh\u00e3o de d\u00f3lares\u00a0(Cerca de R$ 5,5 milh\u00f5es). Pelo Le\u00e3o Caipira, ele anotou seis gols em 20 jogos disputados na S\u00e9rie A do Brasileiro.<\/p>\n\n\n\n<p>Enquanto o atacante veio apenas para compor elenco, a contrata\u00e7\u00e3o mais bomb\u00e1stica fica por conta da chegada de Gerson, ex-Flamengo e que atualmente est\u00e1 no Zenit, da R\u00fassia. Vale lembrar que ele havia deixado o Rubro-Negro ainda no meio do ano passado, mas n\u00e3o se firmou por l\u00e1.<\/p>\n\n\n\n<p>Se antes isso j\u00e1 vinha se tornando uma verdadeira novela, agora est\u00e1 cada vez mais pr\u00f3ximo de um final feliz para o Cruzeiro. O clube chegou a um acordo e vai pagar cerca de 30 milh\u00f5es de euros (R$ 179 milh\u00f5es na cota\u00e7\u00e3o atual) por um contrato de quatro temporadas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pai de Gerson comentou acerto com o Cruzeiro<\/h2>\n\n\n\n<p>Recentemente, Marc\u00e3o Silva, pai de Gerson e que tamb\u00e9m \u00e9 seu empres\u00e1rio, comentou sobre a proximidade do acerto com o Cruzeiro. Ele esteve recentemente na Toca da Raposa, centro de treinamento do clube mineiro.<\/p>\n\n\n\n<p>Muito luta, muita correria. Mas tamb\u00e9m muita felicidade. Agora estamos a detalhes de assinar. Eu estou feliz, me deu crise de riso. Estou com meus advogados, a gente vai comer e dar uma revisada nos contratos. Provavelmente sai hoje! Agora vem aquela parte mais burocr\u00e1tica de revisar contrato. Vamos ver. Com o Zenit, ok!&#8221;, disse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Cruzeiro sob a gest\u00e3o da SAF de Pedrinho BH voltou a ser uma das principais for\u00e7as do futebol brasileiro, muito por conta de seu investimento bastante elevado em contrata\u00e7\u00f5es. Se em 2025 o investimento j\u00e1 havia sido pesado, n\u00e3o vem sendo diferente agora em 2026. Apesar de ainda n\u00e3o ter anunciado nenhum novo refor\u00e7o [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":8719,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-variedades"],"_links":{"self":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/8718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=8718"}],"version-history":[{"count":1,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/8718\/revisions"}],"predecessor-version":[{"id":8720,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/8718\/revisions\/8720"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/8719"}],"wp:attachment":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=8718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=8718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=8718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}