{"id":8869,"date":"2026-01-12T05:40:00","date_gmt":"2026-01-12T08:40:00","guid":{"rendered":"https:\/\/diariodaregiao.audiencelabs.com.br\/?p=8869"},"modified":"2026-01-09T16:39:28","modified_gmt":"2026-01-09T19:39:28","slug":"governo-federal-passa-a-pagar-salario-de-r-8-475-para-aposentados","status":"publish","type":"post","link":"https:\/\/diariodaregiao.audiencelabs.com.br\/governo-federal-passa-a-pagar-salario-de-r-8-475-para-aposentados\/","title":{"rendered":"Governo Federal passa a pagar sal\u00e1rio de R$ 8.475 para aposentados"},"content":{"rendered":"\n<p>O ano de 2026 mal come\u00e7ou e todos os benefici\u00e1rios de qualquer tipo de programa j\u00e1 come\u00e7am a se movimentar em busca do recebimento dos primeiros pagamentos. Os aposentados do Brasil ficam de olho no sal\u00e1rio que ser\u00e1 pago pelo Governo Federal.<\/p>\n\n\n\n<p>Agora em 2026, aposentadorias e pens\u00f5es do Instituto Nacional do Seguro Social (INSS) ser\u00e3o beneficiados com novo teto de R$ 8.475,54 para quem recebe acima do sal\u00e1rio m\u00ednimo. O valor indica o m\u00e1ximo que o INSS poder\u00e1 pagar para segurados que recebem benef\u00edcios previdenci\u00e1rios, como aposentadoria e pens\u00e3o.<\/p>\n\n\n\n<p>O \u00cdndice Nacional de Pre\u00e7os ao Consumidor (INPC) foi usado como base para a defini\u00e7\u00e3o desse reajusta, medindo a infla\u00e7\u00e3o para fam\u00edlias com renda de at\u00e9 cinco sal\u00e1rios m\u00ednimos. Consta-se que o ano de 2025 fechou com a alta de 3,90%.<\/p>\n\n\n\n<p>Com a corre\u00e7\u00e3o definida a partir disso, o teto passa dos atuais R$ 8.157,41 para R$ 8.475,54, um aumento de R$ 318,13 para os segurados que recebem os maiores benef\u00edcios. Ainda h\u00e1 um ponto que os benefici\u00e1rios devem ficar atentos em rela\u00e7\u00e3o ao pagamento.<\/p>\n\n\n\n<p>Al\u00e9m disso, foi comunicado que o reajuste ser\u00e1 pago integralmente a quem j\u00e1 recebia benef\u00edcio acima de um sal\u00e1rio m\u00ednimo em 1.\u00ba de janeiro de 2025, enquanto os que come\u00e7aram a receber a aposentadoria ou pens\u00e3o ao longo do ano passado ter\u00e1 o aumento proporcional aos meses em que o benef\u00edcio foi pago.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quando os valores ser\u00e3o pagos aos aposentados?<\/h2>\n\n\n\n<p>O pagamento dos benef\u00edcios com os novos valores segue um calend\u00e1rio escalonado pelo n\u00famero final do cart\u00e3o do segurado. Os valores relativos ao sal\u00e1rio m\u00ednimo come\u00e7aram a ser pagos em 26 de janeiro, e os benef\u00edcios acima do piso com reajuste ser\u00e3o pagos de 2 a 6 de fevereiro de 2026.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ano de 2026 mal come\u00e7ou e todos os benefici\u00e1rios de qualquer tipo de programa j\u00e1 come\u00e7am a se movimentar em busca do recebimento dos primeiros pagamentos. Os aposentados do Brasil ficam de olho no sal\u00e1rio que ser\u00e1 pago pelo Governo Federal. Agora em 2026, aposentadorias e pens\u00f5es do Instituto Nacional do Seguro Social (INSS) [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":8874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-variedades"],"_links":{"self":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/8869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=8869"}],"version-history":[{"count":1,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/8869\/revisions"}],"predecessor-version":[{"id":8875,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/8869\/revisions\/8875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/8874"}],"wp:attachment":[{"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=8869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=8869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodaregiao.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=8869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}